{"id":3620,"date":"2020-01-27T09:01:07","date_gmt":"2020-01-27T08:01:07","guid":{"rendered":"https:\/\/www.onyx-cie.ch\/retrocessions-gestion-de-fortune\/"},"modified":"2020-01-27T09:06:14","modified_gmt":"2020-01-27T08:06:14","slug":"retrocessions-gestion-de-fortune","status":"publish","type":"post","link":"https:\/\/www.onyx-cie.ch\/it\/retrocessions-gestion-de-fortune\/","title":{"rendered":"Les r\u00e9trocessions en mati\u00e8re de gestion de fortune"},"content":{"rendered":"<p>Similaire \u00e0 la croisi\u00e8re offerte aux m\u00e9decins par les fabricants de m\u00e9dicaments, le syst\u00e8me des r\u00e9trocessions en mati\u00e8re bancaire, est longtemps rest\u00e9 tabou en Suisse. Il faut dire que les montants revers\u00e9s par les banques aux gestionnaires de fortune en fonction du volume d\u2019affaires g\u00e9n\u00e9r\u00e9, pouvait atteindre des chiffres colossaux et personne n\u2019avait int\u00e9r\u00eat \u00e0 d\u00e9baller cette pratique sur la place publique.<\/p>\n<p>Ainsi, s\u2019agissant par exemple des r\u00e9trocessions portant sur les honoraires de courtage, la banque reversait g\u00e9n\u00e9ralement au gestionnaire entre 30% et 50% des frais factur\u00e9s au client pour l\u2019op\u00e9ration boursi\u00e8re.<\/p>\n<p>Il faut remonter \u00e0 2006 pour retrouver les premi\u00e8res r\u00e8gles en la mati\u00e8re, d\u00e9finies par le Tribunal f\u00e9d\u00e9ral. Depuis, celles-ci n\u2019ont jamais cess\u00e9 de devenir plus restrictives au point qu\u2019elles sont depuis le 1<sup>er<\/sup> janvier 2020 formellement codifi\u00e9es dans la loi. Comme nous le verrons ci-apr\u00e8s, en l\u2019espace de 13 ans, nous sommes pass\u00e9s d\u2019une source de revenu usuelle et normale pour les interm\u00e9diaires financiers \u00e0 la commission d\u2019une infraction p\u00e9nale.<\/p>\n<p>Notre family office fait le point sur cette pratique aujourd\u2019hui quasiment bannie et appartenant bient\u00f4t aux livres d\u2019histoire.<\/p>\n<ol>\n<li><u>Quelques remarques pr\u00e9liminaires sur le contrat de gestion de fortune et les r\u00e9trocessions<\/u><\/li>\n<\/ol>\n<p>Pour rappel, le contrat de gestion de fortune se d\u00e9finit comme un contrat par lequel le g\u00e9rant s\u2019engage envers le client, contre r\u00e9mun\u00e9ration, \u00e0 g\u00e9rer de mani\u00e8re professionnelle des instruments financiers (actions, obligations, placements collectifs, etc.) lui appartenant.<\/p>\n<p>Dans le cadre de cet article, il importe peu que les actifs soient d\u00e9pos\u00e9s aupr\u00e8s du g\u00e9rant (lorsque celui-ci est autoris\u00e9 \u00e0 le faire) ou aupr\u00e8s d\u2019une institution tierce (par exemple une banque d\u00e9positaire). Dans la seconde hypoth\u00e8se, le g\u00e9rant ind\u00e9pendant (comme <a href=\"https:\/\/www.onyx-cie.ch\/gestion-de-fortune\/\">Onyx &amp; Cie SA<\/a>) administre les avoirs du client sur la base d\u2019une procuration conf\u00e9r\u00e9e par ce dernier permettant de donner des instructions au tiers d\u00e9positaire pour effectuer les op\u00e9rations d\u2019investissement.<\/p>\n<p>Par ailleurs, il n\u2019est pas relevant que le contrat porte sur une gestion discr\u00e9tionnaire des avoirs ou est limit\u00e9 \u00e0 la simple fourniture de conseils au client (dans ce cas, le client prend lui-m\u00eame les d\u00e9cisions d\u2019investissement \u00e0 effectuer et endosse la pleine responsabilit\u00e9 des placements conseill\u00e9s par le g\u00e9rant, contrairement \u00e0 la situation o\u00f9 c\u2019est le gestionnaire lui-m\u00eame qui d\u00e9cide des op\u00e9rations \u00e0 r\u00e9aliser selon le profil d\u2019investissement du client).<\/p>\n<p>Enfin, on notera que la pratique fait une distinction entre les types de clients auxquels les services sont rendus : on distingue ainsi les clients institutionnels (les fonds de pr\u00e9voyance par exemple) et les clients priv\u00e9s qui ne sont g\u00e9n\u00e9ralement pas des professionnels disposant de connaissances approfondies sur les march\u00e9s financiers.<\/p>\n<p style=\"text-align: center;\"><span style=\"color: #0000ff;\">*****<\/span><\/p>\n<p>Vu la nature professionnelle du contrat de gestion de fortune, ce dernier pr\u00e9voit presque toujours une r\u00e9mun\u00e9ration en faveur du gestionnaire. Il existe diff\u00e9rentes modalit\u00e9s de calcul mais en r\u00e8gle g\u00e9n\u00e9rale celui-ci per\u00e7oit une commission de gestion proportionnelle \u00e0 la valeur des avoirs g\u00e9r\u00e9s, voire alternativement ou en compl\u00e9ment une commission de performance, proportionnelle aux gains r\u00e9alis\u00e9s sur les placements.<\/p>\n<p>Outre la commission de gestion, il est (\u00e9tait ?) fr\u00e9quent que le gestionnaire per\u00e7oive des prestations de la part d\u2019autres interm\u00e9diaires financiers (banques, courtiers, fonds d\u2019investissement, etc.), appel\u00e9es r\u00e9trocessions ou r\u00e9trocommissions (ou encore \u00ab r\u00e9tro \u00bb, soft dollars, finder\u2019s fee, kickback).<\/p>\n<p>Les r\u00e9trocessions repr\u00e9sentent les paiements et autres avantages p\u00e9cuniaires qu\u2019un interm\u00e9diaire financier (par exemple une banque, un fonds de placement) va reverser \u00e0 un tiers (par exemple un gestionnaire de fortune) sur la commission qu\u2019il a encaiss\u00e9e pour la fourniture d\u2019un service financier au client.<\/p>\n<p>Or, comme nous le verrons ci-apr\u00e8s, ces commissions engendrent des conflits d\u2019int\u00e9r\u00eats.<\/p>\n<p>Sur la base d\u2019une relation \u00ab client &#8211; banque d\u00e9positaire &#8211; g\u00e9rant ind\u00e9pendant \u00bb ou \u00ab client \u2013 banque &#8211; distributeur de produits financiers \u00bb, on distingue principalement trois types de r\u00e9trocessions :<\/p>\n<p>&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0 Celles tout d\u2019abord vers\u00e9es sur des op\u00e9rations de d\u00e9p\u00f4ts, par exemple lorsque le gestionnaire apporte un nouveau client ou des fonds additionnels \u00e0 la banque d\u00e9positaire et re\u00e7oit \u00e0 cet effet une r\u00e9mun\u00e9ration. Le risque ici est que le g\u00e9rant ne recommande pas au client la banque la mieux adapt\u00e9e pour lui mais celle qui lui offre les finder\u2019s fees les plus importants.<\/p>\n<p>&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0 Viennent ensuite les r\u00e9trocessions vers\u00e9es sur des op\u00e9rations de commerce, soit la compensation pour des transactions bancaires comme par exemple l\u2019achat et la vente de titres. Plus le nombre de transactions est \u00e9lev\u00e9, plus le client paie des frais de courtage et plus la banque reverse au gestionnaire un montant important sur les frais encaiss\u00e9s. On parle dans cette hypoth\u00e8se de churning (ou barattage), les placements effectu\u00e9s par le g\u00e9rant et les mouvements dans le portefeuille sont inutiles pour le client et ne pr\u00e9sentent aucun int\u00e9r\u00eat \u00e9conomique mais visent en r\u00e9alit\u00e9 qu\u2019\u00e0 augmenter le montant des r\u00e9trocommissions de la banque.<\/p>\n<p>&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0 Enfin, on trouve les r\u00e9trocessions vers\u00e9es sur la vente de produits financiers. Le gestionnaire respectivement la banque (sur la base d\u2019un contrat de distribution) se voit reverser par exemple dans le cas d\u2019un fonds d\u2019investissement une partie des frais que le client a d\u00fb payer (le TER). Le risque ici est que le g\u00e9rant\/la banque ne s\u00e9lectionne pas les produits les mieux adapt\u00e9s au profil de risque du client.<\/p>\n<p>On rel\u00e8vera qu\u2019une r\u00e9trocession peut \u00e9galement \u00eatre pay\u00e9e \u00ab en interne \u00bb par exemple lorsque le d\u00e9partement des fonds d\u2019investissement reverse la somme convenue au d\u00e9partement de la gestion de fortune d\u2019une m\u00eame banque.<\/p>\n<p>Au vu de ce qui pr\u00e9c\u00e8de, les r\u00e9trocessions sont-elles l\u00e9gales ? Si oui \u00e0 quelles conditions et quelles sont alors les obligations de l\u2019interm\u00e9diaire financier ?<\/p>\n<p>Notre family office vous dit tout sur le sujet !<\/p>\n<h2><span style=\"color: #0000ff;\"><u>1. Les r\u00e9trocessions sous l\u2019angle du droit civil<\/u><\/span><\/h2>\n<p>Le <a href=\"https:\/\/www.admin.ch\/opc\/fr\/classified-compilation\/19110009\/index.html\">Code des obligations suisse (CO)<\/a> ne traite pas express\u00e9ment du contrat de gestion de fortune. Toutefois, sans rentrer dans des d\u00e9bats doctrinaux qui ont d\u00e9j\u00e0 fait couler beaucoup d\u2019encre, on s\u2019accorde g\u00e9n\u00e9ralement \u00e0 dire (doctrine majoritaire et jurisprudence) que les r\u00e8gles sur le mandat sont applicables. D\u00e8s lors, la responsabilit\u00e9 et les principaux devoirs du g\u00e9rant sont r\u00e9gis par les articles 394 ss CO. Il en va de m\u00eame s\u2019agissant de la relation de conseil en placements d\u00e9crite ci-dessus.<\/p>\n<p>Au niveau de ses obligations contractuelles, le g\u00e9rant de fortune poss\u00e8de un devoir d\u2019information vis-\u00e0-vis du client (article 398 CO). En clair, il doit renseigner celui-ci, de <u>sa propre initiative<\/u>, sur tous <u>les faits importants<\/u> concernant le contrat, tant au niveau de sa conclusion que dans le cadre de son ex\u00e9cution. Sont consid\u00e9r\u00e9s comme importants, les faits susceptibles de modifier la volont\u00e9 contractuelle du mandant ou qui pourrait l\u2019inciter \u00e0 changer, donner ou retirer des instructions.<\/p>\n<p>Ainsi, le gestionnaire de fortune doit informer le client sur les co\u00fbts de l\u2019activit\u00e9 d\u00e9ploy\u00e9e et sur les frais aff\u00e9rents aux transactions initi\u00e9es par le g\u00e9rant dans le cadre du mandat. Le mandataire est donc tenu d\u2019informer ses clients sur sa r\u00e9mun\u00e9ration directe (ses honoraires) et indirecte (les r\u00e9trocessions). L\u2019information doit \u00eatre exacte, compl\u00e8te et claire.<\/p>\n<p>A c\u00f4t\u00e9 de ce devoir, vient s\u2019ajouter une obligation de rendre compte et de restitution (article 400 CO) : ainsi, \u00ab le mandataire est tenu, <u>\u00e0 la demande du mandant<\/u>, de lui rendre en tout temps compte de sa gestion et de lui restituer tout ce qu\u2019il a re\u00e7u de ce chef, \u00e0 quelque titre que ce soit. \u00bb<\/p>\n<p>Le but de l\u2019obligation de rendre compte est de permettre au client de contr\u00f4ler la bonne et fid\u00e8le ex\u00e9cution du mandat et ainsi de s\u2019assurer que la gestion du g\u00e9rant de fortune est conforme au contrat. L\u2019obligation de restituer (documents, avoirs, etc.) vise quant \u00e0 elle \u00e0 ce que le patrimoine du gestionnaire ne soit pas enrichi par l\u2019ex\u00e9cution du mandat autrement que par la compensation convenue entre les parties. En clair, mis \u00e0 part les honoraires \u00e9tablis entre le client et son gestionnaire, ce dernier ne doit rien perdre ni gagner avec le mandat.<\/p>\n<p>Ce devoir de restitution concerne aussi bien les avoirs confi\u00e9s au gestionnaire par le client que tout ce que le premier peut avoir acquis ou re\u00e7u lors de la conclusion ou de l\u2019ex\u00e9cution du contrat.<\/p>\n<p>Les r\u00e9trocessions font typiquement partie des avantages indirects vis\u00e9s par l\u2019article 400 CO. Ils ont fait couler beaucoup d\u2019encre au cours de la derni\u00e8re d\u00e9cennie jusqu\u2019\u00e0 ce que le Tribunal f\u00e9d\u00e9ral r\u00e8gle progressivement d\u00e9finitivement la question.<\/p>\n<p>Ainsi, dans un premier arr\u00eat du 22 mars 2006 (<a href=\"http:\/\/relevancy.bger.ch\/php\/aza\/http\/index.php?lang=fr&amp;type=highlight_simple_query&amp;page=1&amp;from_date=&amp;to_date=&amp;sort=relevance&amp;insertion_date=&amp;query_words=4c.432%2F2005&amp;rank=1&amp;azaclir=aza&amp;highlight_docid=aza%3A%2F%2F22-03-2006-4C-432-2005&amp;number_of_ranks=2\">ATF 132 III 460<\/a> ; JdT 2008 I 58) qui a pos\u00e9 les premiers jalons sur lesquels la jurisprudence ult\u00e9rieure en mati\u00e8re de r\u00e9trocessions s\u2019est d\u00e9velopp\u00e9e, le Tribunal f\u00e9d\u00e9ral a jug\u00e9 que le gestionnaire de fortune ind\u00e9pendant (le mandataire) est tenu de restituer au client (le mandant) toutes <u>les valeurs qui pr\u00e9sentent<\/u> <u>un lien intrins\u00e8que avec l\u2019ex\u00e9cution du mandat<\/u>. Partant, les r\u00e9trocessions comme par exemple les finders\u2019 fees que le g\u00e9rant touche de la banque pour l\u2019apport d\u2019un nouveau client doivent \u00eatre restitu\u00e9es \u00e0 l\u2019investisseur conform\u00e9ment \u00e0 l\u2019article 400 al. 1 CO. La pr\u00e9somption d\u2019un consentement tacite du client de m\u00eame que le fait que cela soit une pratique r\u00e9pandue en Suisse (r\u00e9mun\u00e9ration usuelle de la branche) ne permettent pas au g\u00e9rant de s\u2019approprier d\u2019\u00e9ventuelles r\u00e9trocessions sans en toucher mot \u00e0 son client.<\/p>\n<p>Apr\u00e8s avoir pos\u00e9 ce principe (d\u00e9j\u00e0 tr\u00e8s largement admis \u00e0 l\u2019\u00e9poque par la pratique), notre Haute Cour s\u2019est pench\u00e9e sur la question de la validit\u00e9 d\u2019une renonciation pr\u00e9alable au droit \u00e0 la restitution (jusqu\u2019alors l\u2019article 400 CO \u00e9tait consid\u00e9r\u00e9 comme de droit imp\u00e9ratif). Elle a estim\u00e9 que les parties sont libres de convenir d\u2019une solution divergente \u00e0 condition que le client soit inform\u00e9 <u>pr\u00e9alablement<\/u> <u>de mani\u00e8re compl\u00e8te et v\u00e9ridique<\/u> sur les r\u00e9trocessions per\u00e7ues par le gestionnaire. La <u>volont\u00e9 du client doit \u00e9galement \u00eatre clairement manifest\u00e9e<\/u>.<\/p>\n<p>Le Tribunal f\u00e9d\u00e9ral ne pr\u00e9cise toutefois pas \u00e0 quel point le client doit \u00eatre \u00e9clair\u00e9, se bornant \u00e0 \u00e9noncer que les informations fournies doivent permettre au client d\u2019estimer le montant des r\u00e9trocessions. Ce montant d\u00e9pend lui-m\u00eame de nombreux facteurs comme la masse des avoirs sous gestion, le nombre de transactions effectu\u00e9es, les termes des accords sur la base desquels ces r\u00e9mun\u00e9rations sont vers\u00e9es, etc., si bien qu\u2019il n\u2019est pas possible de consid\u00e9rer comme usuelle la renonciation du mandant \u00e0 la reddition de comptes et \u00e0 l\u2019appropriation des r\u00e9trocessions par le gestionnaire. Le client ne peut en effet conna\u00eetre ni contr\u00f4ler l\u2019ampleur des sommes vers\u00e9es.<\/p>\n<p>Suite \u00e0 cet arr\u00eat, la doctrine s\u2019est d\u00e9chir\u00e9e sur la port\u00e9e exacte de l\u2019expression \u00ab valablement inform\u00e9 \u00bb. Il aura fallu attendre le 29 ao\u00fbt 2011 (<a href=\"http:\/\/relevancy.bger.ch\/php\/aza\/http\/index.php?lang=fr&amp;type=highlight_simple_query&amp;page=1&amp;from_date=&amp;to_date=&amp;sort=relevance&amp;insertion_date=&amp;top_subcollection_aza=all&amp;query_words=4A_266%2F2010&amp;rank=1&amp;azaclir=aza&amp;highlight_docid=aza%3A%2F%2F29-08-2011-4A_266-2010&amp;number_of_ranks=1\">ATF 137 III 393<\/a> ; JdT 2012 II 168) pour que le Tribunal f\u00e9d\u00e9ral d\u00e9cide qu\u2019une renonciation \u00e0 la restitution des r\u00e9trocessions vers\u00e9es au gestionnaire n\u2019est valable que si le client a \u00e9t\u00e9 <u>au pr\u00e9alable<\/u>, inform\u00e9 1) <u>des param\u00e8tres essentiels de l\u2019accord<\/u> sur la base duquel les r\u00e9trocessions sont calcul\u00e9es et pay\u00e9es et 2) <u>du montant pr\u00e9visible de celles-ci<\/u>, par la communication au client de l\u2019ampleur (sous forme de marge de pourcentage) que les r\u00e9trocessions repr\u00e9sentent par rapport \u00e0 la fortune g\u00e9r\u00e9e. Dans cette mesure, le client peut alors appr\u00e9cier la r\u00e9mun\u00e9ration globale (directe et indirecte) du mandataire et avoir une id\u00e9e claire sur les conflits d\u2019int\u00e9r\u00eats auxquels ce dernier est expos\u00e9.<\/p>\n<p>Notre Cour supr\u00eame ne s\u2019arr\u00eate pas l\u00e0 mais \u00e9tablit aussi la n\u00e9cessit\u00e9 d\u2019informer son client, s\u2019il est compl\u00e8tement inexp\u00e9riment\u00e9 et ignorant, de mani\u00e8re d\u00e9taill\u00e9e sur tous les points g\u00e9n\u00e9rateurs de conflits d\u2019int\u00e9r\u00eats qui peuvent d\u00e9couler du versement de r\u00e9trocessions au tiers g\u00e9rant. Face \u00e0 un client exp\u00e9riment\u00e9, de telles explications suppl\u00e9mentaires ne sont pas n\u00e9cessaires, le gestionnaire peut se contenter d\u2019indiquer les informations mentionn\u00e9es ci-dessus.<\/p>\n<p>Enfin, un jugement du Tribunal f\u00e9d\u00e9ral du 16 juin 2017 (<a href=\"http:\/\/relevancy.bger.ch\/php\/aza\/http\/index.php?lang=fr&amp;type=highlight_simple_query&amp;page=1&amp;from_date=&amp;to_date=&amp;sort=relevance&amp;insertion_date=&amp;top_subcollection_aza=all&amp;query_words=4A_508%2F2016&amp;rank=1&amp;azaclir=aza&amp;highlight_docid=aza%3A%2F%2F16-06-2017-4A_508-2016&amp;number_of_ranks=1\">ATF 143 III 348<\/a>) vient compl\u00e9ter les normes de droit priv\u00e9 en mati\u00e8re de r\u00e9trocessions, tranchant la question du d\u00e9lai de prescription. Ainsi, la pr\u00e9tention du client en restitution des r\u00e9trocessions se prescrit par 10 ans (et non 5 ans en application de l\u2019article 128 alin\u00e9a 1 CO). Chaque r\u00e9ception d\u2019une somme \u00e0 restituer fait partir un nouveau d\u00e9lai de 10 ans, \u00e9tant pr\u00e9cis\u00e9 qu\u2019en g\u00e9n\u00e9ral les clauses de renoncement aux r\u00e9trocessions que les gestionnaires de fortune font signer aux clients ne sont valables que pour le futur.<\/p>\n<p><img decoding=\"async\" class=\"fusion-preview-image aligncenter\" src=\"https:\/\/www.onyx-cie.ch\/wp-content\/uploads\/2020\/01\/Retrocessions-scaled.jpg\" sizes=\"\" srcset=\"\" alt=\"\" width=\"674\" height=\"287\" \/><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #0000ff;\">*****<\/span><\/p>\n<p>Les r\u00e9trocessions provenant de la distribution de produits financiers ont \u00e9galement fait l\u2019objet de deux jurisprudences divergentes du Tribunal f\u00e9d\u00e9ral.<\/p>\n<p>Dans un premier <a href=\"http:\/\/relevancy.bger.ch\/php\/aza\/http\/index.php?lang=fr&amp;type=highlight_simple_query&amp;page=1&amp;from_date=&amp;to_date=&amp;sort=relevance&amp;insertion_date=&amp;top_subcollection_aza=all&amp;query_words=6B_223%2F2010&amp;rank=1&amp;azaclir=aza&amp;highlight_docid=aza%3A%2F%2F13-01-2011-6B_223-2010&amp;number_of_ranks=1\">arr\u00eat du 13 janvier 2011 (6B_223\/2010)<\/a>, notre Haute Cour a examin\u00e9 la question des r\u00e9trocessions pay\u00e9es \u00e0 une banque pour la distribution de produits structur\u00e9s au client. Les juges de Mont-Repos ont retenu qu\u2019il n\u2019existait aucune relation contractuelle entre le promoteur et le client, mais uniquement un contrat (mandat\u00a0?) entre ce dernier et la banque et un contrat de distribution entre celle-ci et le promoteur. Ainsi, contrairement au gestionnaire de fortune ind\u00e9pendant, la banque ne per\u00e7oit pas les r\u00e9trocessions du chef de sa relation avec le client mais \u00e0 titre de contre-prestation pour des services rendus au promoteur en mati\u00e8re de distribution de produits financiers. En clair, le Tribunal f\u00e9d\u00e9ral fait une distinction, pr\u00f4n\u00e9e \u00e0 l\u2019\u00e9poque tant par la Swiss Funds &amp; Asset Management Association (circulaire n\u00b022\/06 du 5 d\u00e9cembre 2006) que par les Directives sur le mandat de gestion de fortune de l\u2019Association Suisse des Banquiers (chiffre 16), entre services \u00ab intrins\u00e8quement li\u00e9s au mandat \u00bb (qui tombent sous le coup de l\u2019obligation de restitution selon l\u2019ATF 132 III 460) et ceux fournis seulement \u00ab dans le cadre de l\u2019ex\u00e9cution du mandat \u00bb (par exemple les activit\u00e9s promotionnelles ou la mise \u00e0 disposition d\u2019informations sur le produit financier en question). Partant dans cette derni\u00e8re hypoth\u00e8se, les r\u00e9trocessions vers\u00e9es en l\u2019esp\u00e8ce ne devaient pas \u00eatre restitu\u00e9es au client.<\/p>\n<p>Dans un second arr\u00eat du 30 octobre 2012 (<a href=\"http:\/\/relevancy.bger.ch\/php\/aza\/http\/index.php?lang=fr&amp;type=highlight_simple_query&amp;page=1&amp;from_date=&amp;to_date=&amp;sort=relevance&amp;insertion_date=&amp;top_subcollection_aza=all&amp;query_words=4A_127%2F2012&amp;rank=1&amp;azaclir=aza&amp;highlight_docid=aza%3A%2F%2F30-10-2012-4A_127-2012&amp;number_of_ranks=1\">ATF 138 III 755<\/a> ; JdT 2014 II 241), le Tribunal f\u00e9d\u00e9ral a op\u00e9r\u00e9 un revirement de jurisprudence, abolissant la distinction op\u00e9r\u00e9e ci-dessus et estimant que l\u2019activit\u00e9 de distribution de produits financiers pr\u00e9sentait un risque de conflits d\u2019int\u00e9r\u00eats similaire \u00e0 celui du gestionnaire de fortune ind\u00e9pendant qui re\u00e7oit des r\u00e9trocessions. Ainsi, en cas de prestations per\u00e7ues de tiers, un lien intrins\u00e8que peut d\u00e9j\u00e0 \u00eatre admis s\u2019il existe un risque que cette prestation am\u00e8ne le mandataire \u00e0 ne pas suffisamment prendre en compte les int\u00e9r\u00eats du mandant. En conclusion, faute d\u2019informations appropri\u00e9es au client, les r\u00e9trocessions provenant de la distribution de produits financiers sont \u00e9galement soumises \u00e0 restitution. Il n\u2019est \u00e9galement pas relevant que le distributeur et le promoteur appartiennent au m\u00eame groupe financier ou non.<\/p>\n<h2><span style=\"color: #0000ff;\"><u>2. Les r\u00e9trocessions sous l\u2019angle du droit p\u00e9nal<\/u><\/span><\/h2>\n<p>La saga des r\u00e9trocessions aurait pu s\u2019arr\u00eater l\u00e0, que nenni\u2026 En effet, notre Haute Cour a jug\u00e9 (arr\u00eats <a href=\"https:\/\/www.bger.ch\/ext\/eurospider\/live\/fr\/php\/aza\/http\/index.php?highlight_docid=aza%3A%2F%2F16-03-2015-6B_845-2014&amp;lang=fr&amp;type=show_document&amp;zoom=YES&amp;\">6B_845\/2014 du 16 mars 2015<\/a> et <a href=\"https:\/\/www.bger.ch\/ext\/eurospider\/live\/fr\/php\/aza\/http\/index.php?highlight_docid=aza%3A%2F%2F14-08-2018-6B_689-2016&amp;lang=fr&amp;type=show_document&amp;zoom=YES&amp;\">6B_689\/2016 du 14 ao\u00fbt 2018<\/a>) que non seulement le fait de <u>conserver les r\u00e9trocessions<\/u> pouvait constituer une infraction de gestion d\u00e9loyale (article 158 <a href=\"https:\/\/www.admin.ch\/opc\/fr\/classified-compilation\/19370083\/index.html\">Code p\u00e9nal suisse)<\/a> mais \u00e9galement <u>la violation de l\u2019obligation d\u2019information <\/u>du client d\u00e9j\u00e0 ! Parce faute d\u2019\u00eatre inform\u00e9, le mandant ne peut pas faire valoir ses droits, ce dont le gestionnaire r\u00e9pond \u00e0 titre de garant.<\/p>\n<p>Pour rappel l\u2019article 158 CP stipule que <em>\u00ab celui qui, en vertu de la loi, d\u2019un mandat officiel ou d\u2019un acte juridique, est tenu de g\u00e9rer les int\u00e9r\u00eats p\u00e9cuniaires d\u2019autrui ou de veiller sur leur gestion et qui, en violation de ses devoirs, aura port\u00e9 atteinte \u00e0 ces int\u00e9r\u00eats ou aura permis qu\u2019ils soient l\u00e9s\u00e9s sera puni d\u2019une peine privative de libert\u00e9 de trois ans au plus ou d\u2019une peine p\u00e9cuniaire.<\/em> [\u2026]<em> Si l\u2019auteur a agi dans le dessein de se procurer ou de procurer \u00e0 un tiers un enrichissement ill\u00e9gitime, le juge pourra prononcer une peine privative de libert\u00e9 de un \u00e0 cinq ans. \u00bb<\/em><\/p>\n<p>A noter que le gestionnaire de fortune\/la banque est expos\u00e9 \u00e0 la norme p\u00e9nale depuis le 1er arr\u00eat du Tribunal f\u00e9d\u00e9ral en la mati\u00e8re, c\u2019est-\u00e0-dire depuis 2006, alors m\u00eame qu\u2019\u00e0 cette \u00e9poque la jurisprudence \u00e9tait encore extr\u00eamement floue ! Aussi la prescription p\u00e9nale n\u2019est ici pas de 10 ans comme en mati\u00e8re civile mais de 15 ans.<\/p>\n<p>Enfin on rel\u00e8vera que d\u2019autres dispositions p\u00e9nales sont susceptibles de rentrer en consid\u00e9ration comme par exemple l\u2019article 322octies CP qui r\u00e9prime l\u2019infraction de corruption priv\u00e9e, soit celui qui <em>\u00ab offre, promet ou octroie un avantage indu \u00e0 un employ\u00e9, un associ\u00e9, un mandataire ou un autre auxiliaire d\u2019autrui dans le secteur priv\u00e9, en faveur de cette personne ou d\u2019un tiers, pour l\u2019ex\u00e9cution ou l\u2019omission d\u2019un acte en relation avec son activit\u00e9 professionnelle ou commerciale et qui est contraire \u00e0 ses devoirs ou d\u00e9pend de son pouvoir d\u2019appr\u00e9ciation est puni d\u2019une peine privative de libert\u00e9 de trois ans au plus ou d\u2019une peine p\u00e9cuniaire. \u00bb<\/em><\/p>\n<p>L\u2019article 322novies CP s\u2019applique quant \u00e0 lui \u00e0 celui qui sollicite, se fait promettre ou accepte, en sa faveur ou en faveur d\u2019un tiers un avantage indu.<\/p>\n<h2><span style=\"color: #0000ff;\"><u>3. Les r\u00e9trocessions sous l\u2019angle du droit administratif (r\u00e8glementaire)<\/u><\/span><\/h2>\n<p>Le l\u00e9gislateur et les organismes d\u2019autor\u00e9gulation ont fini par \u00ab\u00a0boucler la boucle\u00a0\u00bb en la mati\u00e8re. On distingue ainsi\u00a0:<\/p>\n<h3><span style=\"color: #0000ff;\"><em><u>A. Les normes \u00e9dict\u00e9es par le l\u00e9gislateur<\/u><\/em><\/span><\/h3>\n<p>Tout d\u2019abord, la <a href=\"https:\/\/www.finma.ch\/fr\/\">FINMA<\/a> a publi\u00e9 en d\u00e9cembre 2008 la <a href=\"https:\/\/www.finma.ch\/fr\/documentation\/circulaires\/\">Circulaire 09\/1 concernant les r\u00e8gles-cadres relatives \u00e0 la gestion de fortune<\/a>. Celle-ci est entr\u00e9e en vigueur au 1<sup>er<\/sup> janvier 2009 (puis r\u00e9vis\u00e9e en 2013 et en 2016) et s\u2019impose \u00e0 l\u2019ensemble des professionnels de la branche (banques, n\u00e9gociants, fonds de placement, etc.), y compris aux g\u00e9rants ind\u00e9pendants, en tant que seuil minimum commun pour la reconnaissance par la FINMA des r\u00e8gles de conduite \u00e9dict\u00e9es par les associations professionnelles (autor\u00e9gulation).<\/p>\n<p>La circulaire d\u00e9finit les exigences minimales s\u2019agissant des devoirs de fid\u00e9lit\u00e9, diligence, information et reddition de compte.<\/p>\n<p>S\u2019agissant des r\u00e9trocessions re\u00e7ues de tiers, le gestionnaire doit d\u00e9voiler la nature, les modalit\u00e9s et les \u00e9l\u00e9ments de sa r\u00e9mun\u00e9ration.<\/p>\n<p>Le contrat de gestion de fortune (un renvoi aux conditions g\u00e9n\u00e9rales n\u2019est pas suffisant) doit en particulier d\u00e9finir qui est le b\u00e9n\u00e9ficiaire de toutes les prestations re\u00e7ues de tiers <u>en relation \u00e9troite avec l&#8217;ex\u00e9cution du mandat ou \u00e0 l&#8217;occasion de son ex\u00e9cution<\/u> (le texte va ici plus loin que l\u2019ATF 132 III 460).<\/p>\n<p>Le mandataire doit informer ses clients sur les param\u00e8tres de calcul des r\u00e9trocessions ainsi que les fourchettes des montants qu\u2019il re\u00e7oit ou \u00e0 recevoir. Pour autant que cela soit possible, il le fait pour chaque cat\u00e9gorie de produit. A la demande de ses clients, le g\u00e9rant de fortune rend en outre compte de l&#8217;importance des prestations d\u00e9j\u00e0 re\u00e7ues de tiers.<\/p>\n<p>Suite \u00e0 l\u2019arr\u00eat du Tribunal f\u00e9d\u00e9ral du 30 octobre 2012 (ATF 138 III 755), la FINMA a attir\u00e9 l\u2019attention des interm\u00e9diaires financiers sur cet arr\u00eat et a d\u00e9clar\u00e9 que, bien qu\u2019elle ne soit pas comp\u00e9tente pour trancher d\u2019\u00e9ventuels litiges de droit priv\u00e9, elle consid\u00e9rait que le respect des obligations civiles faisait partie int\u00e9grante de la garantie d\u2019une activit\u00e9 irr\u00e9prochable (<a href=\"https:\/\/www.google.ch\/url?sa=t&amp;rct=j&amp;q=&amp;esrc=s&amp;source=web&amp;cd=1&amp;ved=2ahUKEwiX4_ayhprnAhUFalAKHeTwD48QFjAAegQIBBAB&amp;url=https%3A%2F%2Fwww.finma.ch%2Ffr%2F~%2Fmedia%2Ffinma%2Fdokumente%2Fdokumentencenter%2F4dokumentation%2Ffinma-mitteilungen-archiv%2Ffinma-mitteilung-41-2012.pdf%3Fla%3Dfr&amp;usg=AOvVaw0MwxC97owBZ0crq0Gem9EC\">Communication 41\/2012 du 26 novembre 2012<\/a>). Allant tr\u00e8s loin, elle a ainsi exig\u00e9 des banques qu\u2019elles tiennent compte de l\u2019arr\u00eat du Tribunal f\u00e9d\u00e9ral pr\u00e9cit\u00e9, qu\u2019elles contactent les clients potentiellement concern\u00e9s afin de les informer de l\u2019arr\u00eat, qu\u2019elles indiquent aux clients \u00e0 quel service ils peuvent s\u2019adresser afin d\u2019obtenir des renseignements compl\u00e9mentaires et enfin qu\u2019elles communiquent aux clients qui en font la demande le montant des commissions per\u00e7ues.<\/p>\n<p style=\"text-align: center;\"><span style=\"color: #0000ff;\">*****<\/span><\/p>\n<p>La <a href=\"https:\/\/www.admin.ch\/opc\/fr\/classified-compilation\/20152661\/index.html\">Loi sur les services financiers entr\u00e9e en vigueur au 1<sup>er<\/sup> janvier 2020 (LSFin)<\/a> contient quant \u00e0 elle maintenant une disposition sp\u00e9cifique sur les r\u00e9trocessions. En substance, l\u2019article 26 reprend la jurisprudence d\u00e9velopp\u00e9e par le Tribunal f\u00e9d\u00e9ral jusqu\u2019ici et pr\u00e9voit que\u00a0:<\/p>\n<p><em>\u00ab\u00a01 Les prestataires de services financiers peuvent accepter de la part de tiers des r\u00e9mun\u00e9rations li\u00e9es \u00e0 la fourniture de services financiers :<\/em><\/p>\n<ol>\n<li><em> s\u2019ils ont inform\u00e9 express\u00e9ment au pr\u00e9alable les clients de cette r\u00e9mun\u00e9ration et si ceux-ci y ont renonc\u00e9, ou<\/em><\/li>\n<li><em> si la r\u00e9mun\u00e9ration est enti\u00e8rement transf\u00e9r\u00e9e aux clients.<\/em><\/li>\n<\/ol>\n<p><em>2 L\u2019information des clients doit comprendre le type et l\u2019ampleur de la r\u00e9mun\u00e9ration et pr\u00e9c\u00e9der la fourniture du service financier ou la conclusion du contrat. Si le montant ne peut \u00eatre d\u00e9termin\u00e9 \u00e0 l\u2019avance, le prestataire de services financiers communique \u00e0 ses clients les crit\u00e8res de calcul et les ordres de grandeur. Sur demande, le prestataire de services financiers communique les montants effectivement re\u00e7us.<\/em><\/p>\n<p><em>3 Par r\u00e9mun\u00e9ration, on entend les prestations que le prestataire de services financiers re\u00e7oit de tiers en relation avec la fourniture d\u2019un service financier, notamment les commissions de courtage et autres commissions, les provisions, rabais ou autres avantages p\u00e9cuniaires.\u00a0\u00bb<\/em><\/p>\n<p>*****<\/p>\n<p>Par comparaison, l\u2019Union europ\u00e9enne dispose d\u2019une approche bien plus restrictive. En effet, la <a href=\"https:\/\/eur-lex.europa.eu\/legal-content\/FR\/TXT\/?uri=CELEX%3A32014L0065\">Directive 2014\/65\/UE du 15 mai 2014<\/a>, dite MIFID II, introduit (d\u2019une mani\u00e8re critiquable \u00e0 notre sens) une dualit\u00e9 de r\u00e9gime entre d\u2019une part <u>les services d\u2019investissement relevant de conseils en investissement \u00ab\u00a0ind\u00e9pendants\u00a0\u00bb<\/u> et de <u>gestion de portefeuille<\/u> et d\u2019autre part les autres services financiers. S\u2019agissant de la premi\u00e8re cat\u00e9gorie, l\u2019article 24 MIFID II interdit tout simplement la perception et la conservation des commissions ou avantages \u00e0 l\u2019exception de ceux non mon\u00e9taire mineurs susceptibles d\u2019am\u00e9liorer la qualit\u00e9 du service fourni au client.<\/p>\n<p>En ce qui concerne les autres services notamment <u>les conseils en investissement dits \u00ab\u00a0non-ind\u00e9pendants\u00a0\u00bb<\/u>, les r\u00e9trocessions sont autoris\u00e9es \u00e0 conditions que leur perception ne nuise pas \u00e0 l\u2019int\u00e9r\u00eat du client (l\u2019interm\u00e9diaire financier ne doit pas privil\u00e9gier de mani\u00e8re syst\u00e9matique les investissements o\u00f9 les r\u00e9trocessions sont les plus importantes), qu\u2019elles ont pour effet d\u2019am\u00e9liorer la qualit\u00e9 du service au client et que ce dernier soit pr\u00e9alablement inform\u00e9 de leur existence, tant du point de vue de leur nature que de leur montant.<\/p>\n<p>A noter qu\u2019on entend par conseil en placement \u00ab\u00a0ind\u00e9pendant\u00a0\u00bb, une offre de produits provenant de diff\u00e9rentes sources. L\u2019interm\u00e9diaire financier doit \u00e9tudier un large \u00e9ventail de produits financiers suffisamment diversifi\u00e9s (type, \u00e9metteur, nombre, repr\u00e9sentativit\u00e9, etc.) et conseiller l\u2019investissement qui correspond le mieux au profil de l\u2019investisseur. Rien ne doit l\u2019inciter \u00e0 mettre en avant ses propres produits plut\u00f4t que ceux de tiers. <em>A contrario<\/em>, lorsqu\u2019un conseil en placement est donn\u00e9 \u00e0 titre \u00ab\u00a0non-ind\u00e9pendant\u00a0\u00bb, l\u2019interm\u00e9diaire financier, qui doit n\u00e9anmoins s\u2019assurer que le produit correspond au besoin du client, se limitera aux actifs qu\u2019il a lui-m\u00eame d\u00e9velopp\u00e9s et ne prendra pas en compte ceux d\u2019autres institutions financi\u00e8res.<\/p>\n<h3><em><span style=\"color: #0000ff;\"><u>B. Les normes \u00e9dict\u00e9es par les organismes d\u2019autor\u00e9gulation<\/u><\/span><\/em><\/h3>\n<p>L\u2019autor\u00e9gulation est un \u00e9l\u00e9ment important du droit suisse des march\u00e9s financiers. Elle est \u00e0 l&#8217;interm\u00e9diaire entre la r\u00e9glementation de nature autonome et priv\u00e9e et la l\u00e9gislation \u00e9tatique.<\/p>\n<p>Ainsi, le <a href=\"https:\/\/www.vsv-asg.ch\/uploads\/file\/Selbstregulierung\/2017\/vsv_standesregeln_fr_08_2017.pdf\">Code de conduite relatif \u00e0 l\u2019exercice de la profession de g\u00e9rant de fortune ind\u00e9pendant<\/a> de l\u2019<a href=\"https:\/\/www.vsv-asg.ch\/fr\/home\">Association Suisse des G\u00e9rants de fortune<\/a> stipule que (article 6 \u00a7 25)\u00a0:<\/p>\n<p><em>\u00ab\u00a0Le g\u00e9rant de fortune est tenu d\u2019informer ses clients sur ses honoraires ainsi que sur toutes les bonifications de tiers qui lui reviennent ou pourraient lui revenir en lien avec les prestations consid\u00e9r\u00e9es, quel que soit leur fondement juridique. Il les rend attentifs aux conflits d\u2019int\u00e9r\u00eats qui peuvent \u00eatre li\u00e9s \u00e0 la perception de telles bonifications. Lorsque leur montant ne peut pas \u00eatre chiffr\u00e9 \u00e0 l\u2019avance parce qu\u2019il d\u00e9pend d\u2019\u00e9l\u00e9ments ou de r\u00e9sultats futurs, le g\u00e9rant informe de mani\u00e8re compr\u00e9hensible ses clients des param\u00e8tres de calcul et des fourchettes de valeurs des bonifications qu\u2019il re\u00e7oit ou pourrait recevoir de tiers.\u00a0\u00bb<\/em><\/p>\n<p>De son c\u00f4t\u00e9 l\u2019<a href=\"https:\/\/www.swissbanking.org\/fr\/\">Association Suisse des Banquiers<\/a> traite dans ses Directives concernant le mandat de gestion de fortune (version de 2017) les r\u00e9trocessions comme suit\u00a0:<\/p>\n<p><em>\u00ab\u00a0Article 15<\/em><\/p>\n<p><em>Le mandat de gestion de fortune stipule \u00e0 qui reviennent les \u00e9ventuelles prestations de tiers re\u00e7ues par la banque en vertu dudit mandat de gestion de fortune. Cette stipulation n\u2019est pas requise lorsque le mandat de gestion de fortune pr\u00e9voit que la banque investira exclusivement dans des produits sans \u00e9ventuelles prestations de tiers. Pour le cas o\u00f9, dans le cadre d\u2019un tel mandat de gestion de fortune, des prestations de tiers pourraient exceptionnellement \u00eatre per\u00e7ues (p. ex. valeurs souhait\u00e9es par le client ou transfert de valeurs par le client dans le portefeuille sous gestion jusqu\u2019\u00e0 leur arbitrage), une annexe ou une convention s\u00e9par\u00e9e peut r\u00e9gler \u00e0 qui reviennent les \u00e9ventuelles prestations de tiers. La banque attire l\u2019attention du client sur les conflits d\u2019int\u00e9r\u00eats susceptibles de r\u00e9sulter de l\u2019acceptation de prestations de tiers (art. 4, al. 2 des pr\u00e9sentes Directives).<\/em><\/p>\n<p><em>Article 16<\/em><\/p>\n<p><em>La banque informe ses clients des param\u00e8tres de calcul et des fourchettes de valeur des prestations qu\u2019elle re\u00e7oit ou pourrait recevoir de tiers. Elle peut, \u00e0 cette fin, regrouper les divers produits en classes de produits.<\/em><\/p>\n<p><em>Article 17<\/em><\/p>\n<p><em>Sur demande, au cas par cas, la banque r\u00e9v\u00e8le aux clients le montant des prestations d\u00e9j\u00e0 re\u00e7ues de tiers.\u00a0\u00bb<\/em><\/p>\n<p>Enfin, s\u2019agissant des fonds de placement, la <a href=\"https:\/\/www.sfama.ch\/fr\">Swiss Funds &amp; Asset Management Association (SFAMA)<\/a> pr\u00e9voit dans sa <a href=\"https:\/\/www.sfama.ch\/fr\/autoregulation-documents-modeles\/transparence\">Directive sur la transparence (2014)<\/a> la possibilit\u00e9 pour les titulaires d\u2019autorisation d\u2019exploiter un placement collectif de verser des r\u00e9trocessions \u00e0 des tiers. Ils doivent indiquer dans les documents du fonds que des r\u00e9trocessions sont vers\u00e9es et pr\u00e9ciser les prestations auxquelles elles correspondent, sans devoir citer nomm\u00e9ment les prestataires ou indiquer le montant vers\u00e9.<\/p>\n<p>C\u2019est aux b\u00e9n\u00e9ficiaires des prestations qu\u2019il appartient d\u2019informer d\u2019eux-m\u00eames gratuitement les investisseurs du montant des r\u00e9mun\u00e9rations qu\u2019ils pourraient recevoir pour la distribution des placements collectifs de capitaux. A la demande des investisseurs, ils doivent communiquer les montants effectivement per\u00e7us. Enfin, l\u2019existence et la nature des conflits d\u2019int\u00e9r\u00eats doivent \u00eatre communiqu\u00e9s.<\/p>\n<h2><span style=\"color: #0000ff;\"><u>4. Conclusion<\/u><\/span><\/h2>\n<p>Il ressort des r\u00e8gles \u00e9nonc\u00e9es ci-dessus que les gestionnaires de fortune r\u00e9cipiendaires de r\u00e9trocessions sont soumis \u00e0 une obligation de fid\u00e9lit\u00e9 envers leurs clients et partant qu\u2019ils doivent se montrer extr\u00eamement prudents s\u2019ils entendent conserver les prestations re\u00e7ues. En particulier, ils doivent informer le mandant de mani\u00e8re exacte et compl\u00e8te (notamment sur les param\u00e8tres de calcul et les montants pr\u00e9visibles \u00e0 recevoir) sur une base <em>ex ante<\/em> et obtenir son consentement \u00e9clair\u00e9.<\/p>\n<p>Dans le cas contraire, ils s\u2019exposent, outre \u00e0 des proc\u00e8s civils, \u00e0 des poursuites p\u00e9nales voire m\u00eame \u00e0 la r\u00e9vocation de leur licence par la FINMA et au paiement d\u2019amendes.<\/p>\n<p>Chez Onyx &amp; Cie SA, le client a toujours \u00e9t\u00e9 au centre de nos pr\u00e9occupations. La confiance, l\u2019ind\u00e9pendance et la transparence sont des <a href=\"https:\/\/www.onyx-cie.ch\/lethique-et-la-philosophie\/\">valeurs essentielles \u00e0 notre family office<\/a>. Nous ne nous contentons pas de satisfaire \u00e0 nos obligations l\u00e9gales mais nous allons au-del\u00e0&#8230; C\u2019est pour cette raison que nous ne percevons et n\u2019acceptons aucune r\u00e9trocession de la part de tiers, que ce soit en mati\u00e8re de gestion de fortune ou s\u2019agissant des autres services que nous proposons. Nous pr\u00e9f\u00e9rons n\u00e9gocier en toute ind\u00e9pendance les meilleurs tarifs pour nos clients afin que ceux-ci soient pleinement satisfaits et renouvellent leur confiance.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Similaire \u00e0 la croisi\u00e8re offerte aux m\u00e9decins par les fabricants de m\u00e9dicaments, le syst\u00e8me des r\u00e9trocessions en mati\u00e8re bancaire, est longtemps rest\u00e9 tabou en Suisse. Il faut dire que les montants revers\u00e9s par les banques aux gestionnaires de fortune en fonction du volume d\u2019affaires g\u00e9n\u00e9r\u00e9, pouvait atteindre des chiffres colossaux et personne n\u2019avait int\u00e9r\u00eat \u00e0<\/p>\n","protected":false},"author":1,"featured_media":3614,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1402],"tags":[1403,1404,956,959,1405,1406,1407,1408,1409,1410,1205,1411,983,1412,1413,1414,1415,1416,1417,997],"class_list":["post-3620","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-reglementation-bancaire-it-2","tag-asb-it","tag-asg-it","tag-banque-it-2","tag-client-it-2","tag-commission-it","tag-conflit-dinterets-it","tag-finders-fee-it","tag-finders-fees-it","tag-finma-it-2","tag-gerant-independant-it","tag-gestion-de-fortune-it","tag-gestion-deloyale-it","tag-gestionnaire-de-fortune-it-2","tag-kickback-it","tag-madataire-it","tag-mandant-it","tag-mandat-it","tag-retrocessions-it","tag-retrocommission-it","tag-tribunal-federal-it"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Les r\u00e9trocessions en mati\u00e8re de gestion de fortune - Family office<\/title>\n<meta name=\"description\" content=\"Les r\u00e9trocessions dans le domaine de la gestion de fortune ont fait couler beaucoup d&#039;encre ces derni\u00e8res ann\u00e9es. Notre family office fait le point en 2020.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.onyx-cie.ch\/it\/retrocessions-gestion-de-fortune\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les r\u00e9trocessions en mati\u00e8re de gestion de fortune - Family office\" \/>\n<meta property=\"og:description\" content=\"Les r\u00e9trocessions dans le domaine de la gestion de fortune ont fait couler beaucoup d&#039;encre ces derni\u00e8res ann\u00e9es. Notre family office fait le point en 2020.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.onyx-cie.ch\/it\/retrocessions-gestion-de-fortune\/\" \/>\n<meta property=\"og:site_name\" content=\"We are an independent family office\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/onyxcie\" \/>\n<meta property=\"article:published_time\" content=\"2020-01-27T08:01:07+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-01-27T08:06:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.onyx-cie.ch\/wp-content\/uploads\/2020\/01\/Retrocessions-1-1024x683.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"onyx\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@onyx_cie\" \/>\n<meta name=\"twitter:site\" content=\"@onyx_cie\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"onyx\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"25 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.onyx-cie.ch\\\/it\\\/retrocessions-gestion-de-fortune\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.onyx-cie.ch\\\/it\\\/retrocessions-gestion-de-fortune\\\/\"},\"author\":{\"name\":\"onyx\",\"@id\":\"https:\\\/\\\/www.onyx-cie.ch\\\/#\\\/schema\\\/person\\\/412e13d665abfd9c634581aceaf8f2d1\"},\"headline\":\"Les r\u00e9trocessions en mati\u00e8re de gestion de fortune\",\"datePublished\":\"2020-01-27T08:01:07+00:00\",\"dateModified\":\"2020-01-27T08:06:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.onyx-cie.ch\\\/it\\\/retrocessions-gestion-de-fortune\\\/\"},\"wordCount\":4950,\"image\":{\"@id\":\"https:\\\/\\\/www.onyx-cie.ch\\\/it\\\/retrocessions-gestion-de-fortune\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.onyx-cie.ch\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/Retrocessions-1.jpg\",\"keywords\":[\"ASB\",\"ASG\",\"banque\",\"client\",\"commission\",\"conflit d&rsquo;int\u00e9r\u00eats\",\"finder&rsquo;s fee\",\"finders&rsquo; fees\",\"FINMA\",\"g\u00e9rant ind\u00e9pendant\",\"gestion de fortune\",\"gestion d\u00e9loyale\",\"gestionnaire de fortune\",\"kickback\",\"madataire\",\"mandant\",\"mandat\",\"r\u00e9trocessions\",\"r\u00e9trocommission\",\"Tribunal f\u00e9d\u00e9ral\"],\"articleSection\":[\"R\u00e8glementation bancaire\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.onyx-cie.ch\\\/it\\\/retrocessions-gestion-de-fortune\\\/\",\"url\":\"https:\\\/\\\/www.onyx-cie.ch\\\/it\\\/retrocessions-gestion-de-fortune\\\/\",\"name\":\"Les r\u00e9trocessions en mati\u00e8re de gestion de fortune - Family office\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.onyx-cie.ch\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.onyx-cie.ch\\\/it\\\/retrocessions-gestion-de-fortune\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.onyx-cie.ch\\\/it\\\/retrocessions-gestion-de-fortune\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.onyx-cie.ch\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/Retrocessions-1.jpg\",\"datePublished\":\"2020-01-27T08:01:07+00:00\",\"dateModified\":\"2020-01-27T08:06:14+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.onyx-cie.ch\\\/#\\\/schema\\\/person\\\/412e13d665abfd9c634581aceaf8f2d1\"},\"description\":\"Les r\u00e9trocessions dans le domaine de la gestion de fortune ont fait couler beaucoup d'encre ces derni\u00e8res ann\u00e9es. Notre family office fait le point en 2020.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.onyx-cie.ch\\\/it\\\/retrocessions-gestion-de-fortune\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.onyx-cie.ch\\\/it\\\/retrocessions-gestion-de-fortune\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.onyx-cie.ch\\\/it\\\/retrocessions-gestion-de-fortune\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.onyx-cie.ch\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/Retrocessions-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.onyx-cie.ch\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/Retrocessions-1.jpg\",\"width\":2560,\"height\":1707,\"caption\":\"Les gestionnaires de fortune doivent informer leurs clients de mani\u00e8re compl\u00e8te et exacte sur les r\u00e9trocessions qu'ils per\u00e7oivent de tiers.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.onyx-cie.ch\\\/it\\\/retrocessions-gestion-de-fortune\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.onyx-cie.ch\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les r\u00e9trocessions en mati\u00e8re de gestion de fortune\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.onyx-cie.ch\\\/#website\",\"url\":\"https:\\\/\\\/www.onyx-cie.ch\\\/\",\"name\":\"We are an independent family office\",\"description\":\"We have a presence in Europe, Asia and Oceania.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.onyx-cie.ch\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.onyx-cie.ch\\\/#\\\/schema\\\/person\\\/412e13d665abfd9c634581aceaf8f2d1\",\"name\":\"onyx\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8e483a197906797d26c364410b3e392c60703fca623efc660672877070023764?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8e483a197906797d26c364410b3e392c60703fca623efc660672877070023764?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8e483a197906797d26c364410b3e392c60703fca623efc660672877070023764?s=96&d=mm&r=g\",\"caption\":\"onyx\"},\"url\":\"https:\\\/\\\/www.onyx-cie.ch\\\/it\\\/author\\\/onyx\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les r\u00e9trocessions en mati\u00e8re de gestion de fortune - Family office","description":"Les r\u00e9trocessions dans le domaine de la gestion de fortune ont fait couler beaucoup d'encre ces derni\u00e8res ann\u00e9es. Notre family office fait le point en 2020.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.onyx-cie.ch\/it\/retrocessions-gestion-de-fortune\/","og_locale":"it_IT","og_type":"article","og_title":"Les r\u00e9trocessions en mati\u00e8re de gestion de fortune - Family office","og_description":"Les r\u00e9trocessions dans le domaine de la gestion de fortune ont fait couler beaucoup d'encre ces derni\u00e8res ann\u00e9es. Notre family office fait le point en 2020.","og_url":"https:\/\/www.onyx-cie.ch\/it\/retrocessions-gestion-de-fortune\/","og_site_name":"We are an independent family office","article_publisher":"https:\/\/www.facebook.com\/onyxcie","article_published_time":"2020-01-27T08:01:07+00:00","article_modified_time":"2020-01-27T08:06:14+00:00","og_image":[{"width":1024,"height":683,"url":"https:\/\/www.onyx-cie.ch\/wp-content\/uploads\/2020\/01\/Retrocessions-1-1024x683.jpg","type":"image\/jpeg"}],"author":"onyx","twitter_card":"summary_large_image","twitter_creator":"@onyx_cie","twitter_site":"@onyx_cie","twitter_misc":{"Scritto da":"onyx","Tempo di lettura stimato":"25 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.onyx-cie.ch\/it\/retrocessions-gestion-de-fortune\/#article","isPartOf":{"@id":"https:\/\/www.onyx-cie.ch\/it\/retrocessions-gestion-de-fortune\/"},"author":{"name":"onyx","@id":"https:\/\/www.onyx-cie.ch\/#\/schema\/person\/412e13d665abfd9c634581aceaf8f2d1"},"headline":"Les r\u00e9trocessions en mati\u00e8re de gestion de fortune","datePublished":"2020-01-27T08:01:07+00:00","dateModified":"2020-01-27T08:06:14+00:00","mainEntityOfPage":{"@id":"https:\/\/www.onyx-cie.ch\/it\/retrocessions-gestion-de-fortune\/"},"wordCount":4950,"image":{"@id":"https:\/\/www.onyx-cie.ch\/it\/retrocessions-gestion-de-fortune\/#primaryimage"},"thumbnailUrl":"https:\/\/www.onyx-cie.ch\/wp-content\/uploads\/2020\/01\/Retrocessions-1.jpg","keywords":["ASB","ASG","banque","client","commission","conflit d&rsquo;int\u00e9r\u00eats","finder&rsquo;s fee","finders&rsquo; fees","FINMA","g\u00e9rant ind\u00e9pendant","gestion de fortune","gestion d\u00e9loyale","gestionnaire de fortune","kickback","madataire","mandant","mandat","r\u00e9trocessions","r\u00e9trocommission","Tribunal f\u00e9d\u00e9ral"],"articleSection":["R\u00e8glementation bancaire"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.onyx-cie.ch\/it\/retrocessions-gestion-de-fortune\/","url":"https:\/\/www.onyx-cie.ch\/it\/retrocessions-gestion-de-fortune\/","name":"Les r\u00e9trocessions en mati\u00e8re de gestion de fortune - Family office","isPartOf":{"@id":"https:\/\/www.onyx-cie.ch\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.onyx-cie.ch\/it\/retrocessions-gestion-de-fortune\/#primaryimage"},"image":{"@id":"https:\/\/www.onyx-cie.ch\/it\/retrocessions-gestion-de-fortune\/#primaryimage"},"thumbnailUrl":"https:\/\/www.onyx-cie.ch\/wp-content\/uploads\/2020\/01\/Retrocessions-1.jpg","datePublished":"2020-01-27T08:01:07+00:00","dateModified":"2020-01-27T08:06:14+00:00","author":{"@id":"https:\/\/www.onyx-cie.ch\/#\/schema\/person\/412e13d665abfd9c634581aceaf8f2d1"},"description":"Les r\u00e9trocessions dans le domaine de la gestion de fortune ont fait couler beaucoup d'encre ces derni\u00e8res ann\u00e9es. Notre family office fait le point en 2020.","breadcrumb":{"@id":"https:\/\/www.onyx-cie.ch\/it\/retrocessions-gestion-de-fortune\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.onyx-cie.ch\/it\/retrocessions-gestion-de-fortune\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.onyx-cie.ch\/it\/retrocessions-gestion-de-fortune\/#primaryimage","url":"https:\/\/www.onyx-cie.ch\/wp-content\/uploads\/2020\/01\/Retrocessions-1.jpg","contentUrl":"https:\/\/www.onyx-cie.ch\/wp-content\/uploads\/2020\/01\/Retrocessions-1.jpg","width":2560,"height":1707,"caption":"Les gestionnaires de fortune doivent informer leurs clients de mani\u00e8re compl\u00e8te et exacte sur les r\u00e9trocessions qu'ils per\u00e7oivent de tiers."},{"@type":"BreadcrumbList","@id":"https:\/\/www.onyx-cie.ch\/it\/retrocessions-gestion-de-fortune\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.onyx-cie.ch\/it\/"},{"@type":"ListItem","position":2,"name":"Les r\u00e9trocessions en mati\u00e8re de gestion de fortune"}]},{"@type":"WebSite","@id":"https:\/\/www.onyx-cie.ch\/#website","url":"https:\/\/www.onyx-cie.ch\/","name":"We are an independent family office","description":"We have a presence in Europe, Asia and Oceania.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.onyx-cie.ch\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.onyx-cie.ch\/#\/schema\/person\/412e13d665abfd9c634581aceaf8f2d1","name":"onyx","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/8e483a197906797d26c364410b3e392c60703fca623efc660672877070023764?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8e483a197906797d26c364410b3e392c60703fca623efc660672877070023764?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8e483a197906797d26c364410b3e392c60703fca623efc660672877070023764?s=96&d=mm&r=g","caption":"onyx"},"url":"https:\/\/www.onyx-cie.ch\/it\/author\/onyx\/"}]}},"_links":{"self":[{"href":"https:\/\/www.onyx-cie.ch\/it\/wp-json\/wp\/v2\/posts\/3620","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.onyx-cie.ch\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.onyx-cie.ch\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.onyx-cie.ch\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.onyx-cie.ch\/it\/wp-json\/wp\/v2\/comments?post=3620"}],"version-history":[{"count":1,"href":"https:\/\/www.onyx-cie.ch\/it\/wp-json\/wp\/v2\/posts\/3620\/revisions"}],"predecessor-version":[{"id":3622,"href":"https:\/\/www.onyx-cie.ch\/it\/wp-json\/wp\/v2\/posts\/3620\/revisions\/3622"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.onyx-cie.ch\/it\/wp-json\/wp\/v2\/media\/3614"}],"wp:attachment":[{"href":"https:\/\/www.onyx-cie.ch\/it\/wp-json\/wp\/v2\/media?parent=3620"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.onyx-cie.ch\/it\/wp-json\/wp\/v2\/categories?post=3620"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.onyx-cie.ch\/it\/wp-json\/wp\/v2\/tags?post=3620"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}